{"id":21234,"date":"2023-11-28T18:39:39","date_gmt":"2023-11-28T21:39:39","guid":{"rendered":"https:\/\/radiosurfm.com\/web\/?p=21234"},"modified":"2023-11-28T18:39:39","modified_gmt":"2023-11-28T21:39:39","slug":"secretaria-de-turismo-se-anuncia-lanzamiento-de-carnavales-evento-navideno-exhibicion-de-tc-2000-y-formula-3","status":"publish","type":"post","link":"https:\/\/radiosurfm.com\/web\/2023\/11\/28\/secretaria-de-turismo-se-anuncia-lanzamiento-de-carnavales-evento-navideno-exhibicion-de-tc-2000-y-formula-3\/","title":{"rendered":"Secretaria de Turismo: se anuncia lanzamiento de carnavales, evento navide\u00f1o, exhibici\u00f3n de TC 2000 y formula 3"},"content":{"rendered":"<p>El 8 de diciembre, la Secretar\u00eda de Turismo presentar\u00e1 en la plaza Mitre, decoraciones navide\u00f1as. El 9 de diciembre, se lanzar\u00e1n los carnavales goyanos. Tambi\u00e9n, en el mes de diciembre, habr\u00e1 una exhibici\u00f3n de autom\u00f3viles de la F\u00f3rmula 3 y el TC 2000. La Municipalidad planifica una serie de eventos para el verano.<\/p>\n<p>El Secretario de Turismo, Sebasti\u00e1n Candia de Biasio anunci\u00f3 que el lanzamiento de los carnavales goyanos se har\u00e1 en el mes de diciembre.<\/p>\n<p>En un contacto con Radio Ciudad, Candia detall\u00f3 que &#8220;el 8 de diciembre vamos a estar abriendo la \u00e9poca navide\u00f1a en plaza Mitre. Con el Intendente estamos armando una decoraci\u00f3n linda que vamos a empezar a mostrar en estos d\u00edas&#8221;.<\/p>\n<p>LANZAMIENTO DE CARNAVALES<\/p>\n<p>&#8220;El 9 de diciembre, tambi\u00e9n en plaza Mitre, vamos a hacer el lanzamiento de los Carnavales. Tenemos a todas las comparsas listas. La decisi\u00f3n del Intendente Mariano Hormaechea es potenciar mucho el carnaval. As\u00ed que ser\u00e1 como la figura de este verano&#8221;, dijo.<\/p>\n<p>EXHIBICI\u00d3N DE AUTOM\u00d3VILES<\/p>\n<p>&#8220;El 17 de diciembre habr\u00e1 un evento de automovilismo. Habr\u00e1 una exhibici\u00f3n de autom\u00f3viles de la F\u00f3rmula 3 y TC 2000. Va a estar toda la movida en plaza Mitre. Aproximadamente a las 18, los veh\u00edculos van a estar transitando por Col\u00f3n y por Belgrano. Ser\u00e1 un evento para toda la familia&#8221;, indic\u00f3 Sebasti\u00e1n Candia De Biasio.<\/p>\n<p>&#8220;Tambi\u00e9n habr\u00e1 una exhibici\u00f3n de karting&#8221;, manifest\u00f3.<\/p>\n<p>PLAYITA Y PARQUE ACU\u00c1TICO<\/p>\n<p>&#8220;Hay muchas cosas pensadas para la playita. Para el Parque Acu\u00e1tico. Tomando ejemplo de lo que vivimos el a\u00f1o pasado, en que nos dimos cuenta de que el ciudadano disfruta de estos espacios, que es una necesidad brindar eventos y shows. Vamos a armar una grilla muy linda, diversa para todos los gustos y para todas las familias, durante toda la temporada de verano&#8221;, expres\u00f3 el funcionario.<\/p>\n<p>OFICINA TUR\u00cdSTICA<\/p>\n<p>Sobre cu\u00e1ndo estar\u00eda terminado el Centro de Informaci\u00f3n Tur\u00edstica, en la zona de La Rotonda, dijo: &#8220;Va a estar todo para mediados de diciembre. Yo calculo que el 15 de diciembre a m\u00e1s tardar va a estar funcionando. La obra viene muy r\u00e1pido y firme. Y dependiendo de si no llueve mucho vamos a estar en ese plazo&#8221;, finaliz\u00f3 el Secretario de Turismo de la Municipalidad de Goya.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El 8 de diciembre, la Secretar\u00eda de Turismo presentar\u00e1 en la plaza Mitre, decoraciones navide\u00f1as. El 9 de diciembre, se lanzar\u00e1n los carnavales goyanos. Tambi\u00e9n, en el mes de diciembre, habr\u00e1 una exhibici\u00f3n de autom\u00f3viles de la F\u00f3rmula 3 y el TC 2000. La Municipalidad planifica una serie de eventos para el verano. El Secretario [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[56,82],"tags":[],"class_list":["post-21234","post","type-post","status-publish","format-standard","hentry","category-locales","category-turismo"],"_links":{"self":[{"href":"https:\/\/radiosurfm.com\/web\/wp-json\/wp\/v2\/posts\/21234","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiosurfm.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiosurfm.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiosurfm.com\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/radiosurfm.com\/web\/wp-json\/wp\/v2\/comments?post=21234"}],"version-history":[{"count":0,"href":"https:\/\/radiosurfm.com\/web\/wp-json\/wp\/v2\/posts\/21234\/revisions"}],"wp:attachment":[{"href":"https:\/\/radiosurfm.com\/web\/wp-json\/wp\/v2\/media?parent=21234"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiosurfm.com\/web\/wp-json\/wp\/v2\/categories?post=21234"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiosurfm.com\/web\/wp-json\/wp\/v2\/tags?post=21234"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}